{"id":924,"date":"2020-05-02T11:38:22","date_gmt":"2020-05-02T14:38:22","guid":{"rendered":"http:\/\/161.35.11.199\/?p=924"},"modified":"2020-05-02T11:38:22","modified_gmt":"2020-05-02T14:38:22","slug":"a-musica","status":"publish","type":"post","link":"https:\/\/www.revistaautadesouza.com\/index.php\/2020\/05\/02\/a-musica\/","title":{"rendered":"A m\u00fasica"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" src=\"http:\/\/161.35.11.199\/wp-content\/uploads\/2020\/05\/musica-1024x683-1.jpg\" alt=\"\" class=\"wp-image-925\" width=\"365\" height=\"243\" srcset=\"https:\/\/www.revistaautadesouza.com\/wp-content\/uploads\/2020\/05\/musica-1024x683-1.jpg 1024w, https:\/\/www.revistaautadesouza.com\/wp-content\/uploads\/2020\/05\/musica-1024x683-1-300x200.jpg 300w, https:\/\/www.revistaautadesouza.com\/wp-content\/uploads\/2020\/05\/musica-1024x683-1-768x512.jpg 768w\" sizes=\"(max-width: 365px) 100vw, 365px\" \/><\/figure><\/div>\n\n\n\n<p>\u201cDiversos trabalhos esp\u00edritas, para maior efici\u00eancia, se beneficiam de m\u00fasica apropriada como, por exemplo: o de vibra\u00e7\u00f5es para curas, o de efeitos f\u00edsicos e outros. A m\u00fasica apropriada n\u00e3o ser\u00e1, naturalmente, a m\u00fasica mundana, f\u00fatil, criada para a dan\u00e7a e o lazer como, tamb\u00e9m n\u00e3o ser\u00e1 aquela criada como express\u00e3o das paix\u00f5es e dos sentimentos animalizados do homem, mas sim a m\u00fasica serena, a melodia suave que enleva o esp\u00edrito e o transporta \u00e0s esferas celestiais, a m\u00fasica harmoniosa cujas vibra\u00e7\u00f5es correspondem \u00e0s dos sentimentos elevados de f\u00e9, amor e alegria. Para preparar o ambiente, auxiliar as vibra\u00e7\u00f5es, para apaziguar os cora\u00e7\u00f5es, para ajudar a emiss\u00e3o de fluidos, para saturar o ambiente de vibra\u00e7\u00f5es elevadas, para tudo serve a m\u00fasica, conquanto n\u00e3o represente um ato ritual, mas simplesmente preparat\u00f3rio e auxiliar, nos trabalhos esp\u00edritas. Nas reuni\u00f5es ou atos p\u00fablicos e piedosos do Espa\u00e7o \u00e9 a m\u00fasica utilizada como alto elemento inspirador e de deleite espiritual, conforme constatamos pelas obras que descrevem a vida nessas esferas felizes.\u201d (Edgard Armond. <em>Trabalhos Pr\u00e1ticos de Espiritismo<\/em>. Cap. V item 18 ). <\/p>\n\n\n\n<h2>o valor da m\u00fasica para o Plano Espiritual<\/h2>\n\n\n\n<p><strong>A M\u00daSICA CELESTE<\/strong><\/p>\n\n\n\n<p>&#8220;A m\u00fasica celeste n\u00e3o \u00e9 produzida por fric\u00e7\u00f5es de arco sobre cordas: tudo \u00e9 flu\u00eddico, tudo \u00e9 espiritual, tudo \u00e9 inspirado pelo pensamento de Deus.&#8221; (L\u00e9on Denis. <em>O Espiritismo na arte<\/em>. 3\u00aa li\u00e7\u00e3o, parte IX)<\/p>\n\n\n\n<p><strong>A m\u00fasica nobre influencia as almas<\/strong><\/p>\n\n\n\n<p>&#8220;[&#8230;] os grandes m\u00fasicos da Terra, [&#8230;] obedecem [&#8230;] a gloriosos impulsos das for\u00e7as do Infinito, porquanto a m\u00fasica na Terra \u00e9, por excel\u00eancia,<br>a arte divina. [&#8230;]<\/p>\n\n\n\n<p>Apenas desse modo podereis compreender a sagrada influ\u00eancia que a m\u00fasica nobre opera nas almas, arrebatando-as, em quaisquer ocasi\u00f5es, \u00e0s ideias indecisas da Terra, para as vibra\u00e7\u00f5es do \u00edntimo com o Infinito.&#8221;(Emmanuel. <em>O consolador.<\/em> Psicografia de Francisco C\u00e2ndido Xavier. Perg. 167)<\/p>\n\n\n\n<p><strong>PODER E A\u00c7\u00c3O DAS VIBRA\u00c7\u00d5ES SONORAS<\/strong> <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" src=\"http:\/\/161.35.11.199\/wp-content\/uploads\/2020\/05\/71d2ec1ce6cd4c9bb0aaedce214ddaf5bf40cb79r1-743-413v2_hq-1.jpg\" alt=\"\" class=\"wp-image-926\" width=\"388\" height=\"215\" srcset=\"https:\/\/www.revistaautadesouza.com\/wp-content\/uploads\/2020\/05\/71d2ec1ce6cd4c9bb0aaedce214ddaf5bf40cb79r1-743-413v2_hq-1.jpg 743w, https:\/\/www.revistaautadesouza.com\/wp-content\/uploads\/2020\/05\/71d2ec1ce6cd4c9bb0aaedce214ddaf5bf40cb79r1-743-413v2_hq-1-300x167.jpg 300w\" sizes=\"(max-width: 388px) 100vw, 388px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Experi\u00eancia de Andr\u00e9 Luiz na Col\u00f4nia Nosso Lar<\/strong><\/p>\n\n\n\n<p>&#8220;Mal terminara a explica\u00e7\u00e3o, as setenta e duas figuras come\u00e7aram a<br>cantar harmonioso hino, repleto de indefin\u00edvel beleza. A fisionomia de<br>Clar\u00eancio, no c\u00edrculo dos vener\u00e1veis companheiros, figurou-se-me tocada de<br>mais intensa luz. O c\u00e2ntico celeste constitu\u00eda-se de notas angelicais, de<br>sublimado reconhecimento. Pairavam no recinto misteriosas vibra\u00e7\u00f5es de<br>paz e de alegria e, quando as notas argentinas fizeram delicioso staccato,<br>desenhou-se ao longe, em plano elevado, um cora\u00e7\u00e3o maravilhosamente<br>azul (1), com estrias douradas. Cariciosa m\u00fasica, em seguida, respondia aos louvores, procedente talvez de esferas distantes. Foi a\u00ed que abundante chuva de flores azuis se derramou sobre n\u00f3s&#8230;&#8221; (Andr\u00e9 Luiz. <em>Nosso lar.<\/em> Psicografia de Francisco C\u00e2ndido Xavier. Cap.3)<\/p>\n\n\n\n<p>A m\u00fasica \u00e9 o <strong>m\u00e9dium<\/strong> da harmonia; ela a recebe e a d\u00e1, como o refletor \u00e9 o <strong>m\u00e9dium<\/strong> da luz, como tu \u00e9s o <strong>m\u00e9dium<\/strong> dos Esp\u00edritos. (Allan Kardec. <em>Obras P\u00f3stumas<\/em>. A m\u00fasica celeste)<\/p>\n\n\n\n<p>&#8220;[&#8230;] o som, o ritmo, a harmonia, s\u00e3o for\u00e7as criadoras. Se n\u00f3s pud\u00e9ssemos calcular o poder das vibra\u00e7\u00f5es sonoras, avaliar sua a\u00e7\u00e3o sobre a mat\u00e9ria flu\u00eddica, sua forma de agrupar os turbilhoes de \u00e1tomos, chegar\u00edamos a um dos segredos da energia espiritual[&#8230;].&#8221; (L\u00e9on Denis. O Espiritismo na arte. Parte VI. A M\u00fasica- parte 1)<\/p>\n\n\n\n<p><strong>A M\u00daSICA EXPRIMINDO BOM \u00c2NIMO E ALEGRIA<\/strong> <\/p>\n\n\n\n<p>&#8220;[&#8230;] a caravana espiritual se dispunha a partir, quando Maria se lembrou dos disc\u00edpulos perseguidos pela crueldade do mundo.[&#8230;] aproximando-se de uma jovem encarcerada, de rosto descarnado e macilento, lhe disse<br>ao ouvido: <strong>\u201cCanta, minha filha! Tenhamos bom \u00e2nimo!<\/strong>\u2026[&#8230;]. Da\u00ed a instantes, seu canto melodioso era acompanhado pelas centenas de vozes dos que choravam no c\u00e1rcere, aguardando o glorioso testemunho. [&#8230;], desde esse dia, nos tormentos mais duros, os disc\u00edpulos de Jesus t\u00eam cantado na Terra, <strong>exprimindo o seu bom \u00e2nimo e a sua alegria,<\/strong> guardando a suave heran\u00e7a de nossa <strong>M\u00e3e Sant\u00edssima<\/strong>.&#8221; (Humberto de Campos. <em>A Boa Nova<\/em>. Psicografia de Francisco C\u00e2ndido Xavier. Cap.30)<\/p>\n\n\n\n<p><strong>A M\u00daSICA NO CENTRO ESP\u00cdRITA<\/strong><\/p>\n\n\n\n<p>Podemos e devemos usar a m\u00fasica dentro de nossas Casas Esp\u00edritas, como forma de divulga\u00e7\u00e3o do Consolador Prometido, tendo, portanto, o cuidado de escolhermos as m\u00fasicas adequadas para o ambiente. T\u00e3o importante quanto levarmos a m\u00fasica para dentro da Casa Esp\u00edrita \u00e9 proporcionarmos aos irm\u00e3os do Centro a oportunidade de cantarem as m\u00fasicas juntamente com a equipe de Alegria Crist\u00e3. Os HIN\u00c1RIOS s\u00e3o a maneira mais f\u00e1cil e pr\u00e1tica de incentivarmos os nossos irm\u00e3os a cantarem conosco, uma vez que de posse das letras das m\u00fasicas fica mais f\u00e1cil aprender a melodia. Heis o valor e import\u00e2ncia do HIN\u00c1RIO, companheiro insepar\u00e1vel da equipe de Alegria Crist\u00e3. <\/p>\n\n\n\n<p>\u201cPreferir as composi\u00e7\u00f5es art\u00edsticas de feitura esp\u00edrita, integral, preservando-se a pureza doutrin\u00e1ria.A Arte enobrecida estende o poder do Amor.\u201d(Andr\u00e9 Luiz.\u00a0<em>Conduta esp\u00edrita<\/em>. Psicografado por Francisco C\u00e2ndido Xavier. Cap. 44)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cDiversos trabalhos esp\u00edritas, para maior efici\u00eancia, se beneficiam de m\u00fasica apropriada como, por exemplo: o de vibra\u00e7\u00f5es para curas, o de efeitos f\u00edsicos e outros. A m\u00fasica apropriada n\u00e3o ser\u00e1, naturalmente, a m\u00fasica mundana, f\u00fatil, criada para a dan\u00e7a e o lazer como, tamb\u00e9m n\u00e3o ser\u00e1 aquela criada como express\u00e3o das paix\u00f5es e dos sentimentos [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":929,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.revistaautadesouza.com\/index.php\/wp-json\/wp\/v2\/posts\/924"}],"collection":[{"href":"https:\/\/www.revistaautadesouza.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revistaautadesouza.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revistaautadesouza.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revistaautadesouza.com\/index.php\/wp-json\/wp\/v2\/comments?post=924"}],"version-history":[{"count":0,"href":"https:\/\/www.revistaautadesouza.com\/index.php\/wp-json\/wp\/v2\/posts\/924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revistaautadesouza.com\/index.php\/wp-json\/wp\/v2\/media\/929"}],"wp:attachment":[{"href":"https:\/\/www.revistaautadesouza.com\/index.php\/wp-json\/wp\/v2\/media?parent=924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revistaautadesouza.com\/index.php\/wp-json\/wp\/v2\/categories?post=924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revistaautadesouza.com\/index.php\/wp-json\/wp\/v2\/tags?post=924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}